{"id":39488,"date":"2023-08-17T16:13:33","date_gmt":"2023-08-17T14:13:33","guid":{"rendered":"https:\/\/ethrat.ch\/?post_type=sciena-post&#038;p=39488"},"modified":"2023-09-15T09:22:28","modified_gmt":"2023-09-15T07:22:28","slug":"limagerie-a-letape-superieure","status":"publish","type":"sciena-post","link":"https:\/\/ethrat.ch\/fr\/scinea-post\/limagerie-a-letape-superieure\/","title":{"rendered":"L\u2019imagerie \u00e0 l\u2019\u00e9tape sup\u00e9rieure"},"content":{"rendered":"","protected":false},"author":11,"featured_media":0,"template":"","meta":{"_acf_changed":false,"_links_to":"","_links_to_target":""},"categories":[468],"sciena_category":[163],"sciena_topic":[],"search-tag":[],"class_list":["post-39488","sciena-post","type-sciena-post","status-publish","hentry","category-news-fr","sciena_category-recherche"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L\u2019imagerie \u00e0 l\u2019\u00e9tape sup\u00e9rieure - Conseil des EPF<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ethrat.ch\/fr\/scinea-post\/limagerie-a-letape-superieure\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019imagerie \u00e0 l\u2019\u00e9tape sup\u00e9rieure - Conseil des EPF\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ethrat.ch\/fr\/scinea-post\/limagerie-a-letape-superieure\/\" \/>\n<meta property=\"og:site_name\" content=\"Conseil des EPF\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-15T07:22:28+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@eth_rat\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ethrat.ch\\\/fr\\\/scinea-post\\\/limagerie-a-letape-superieure\\\/\",\"url\":\"https:\\\/\\\/ethrat.ch\\\/fr\\\/scinea-post\\\/limagerie-a-letape-superieure\\\/\",\"name\":\"L\u2019imagerie \u00e0 l\u2019\u00e9tape sup\u00e9rieure - Conseil des EPF\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ethrat.ch\\\/de\\\/#website\"},\"datePublished\":\"2023-08-17T14:13:33+00:00\",\"dateModified\":\"2023-09-15T07:22:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ethrat.ch\\\/fr\\\/scinea-post\\\/limagerie-a-letape-superieure\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ethrat.ch\\\/fr\\\/scinea-post\\\/limagerie-a-letape-superieure\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ethrat.ch\\\/fr\\\/scinea-post\\\/limagerie-a-letape-superieure\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ethrat.ch\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sciena Post\",\"item\":\"https:\\\/\\\/ethrat.ch\\\/de\\\/scinea-post\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"L\u2019imagerie \u00e0 l\u2019\u00e9tape sup\u00e9rieure\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ethrat.ch\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/ethrat.ch\\\/de\\\/\",\"name\":\"ETH-Rat\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/ethrat.ch\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ethrat.ch\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ethrat.ch\\\/de\\\/#organization\",\"name\":\"ETH-Rat\",\"url\":\"https:\\\/\\\/ethrat.ch\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ethrat.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ethrat.ch\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/logo-white.svg\",\"contentUrl\":\"https:\\\/\\\/ethrat.ch\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/logo-white.svg\",\"width\":283,\"height\":81,\"caption\":\"ETH-Rat\"},\"image\":{\"@id\":\"https:\\\/\\\/ethrat.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/eth_rat\",\"https:\\\/\\\/issuu.com\\\/ethrat\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/eth-rat\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019imagerie \u00e0 l\u2019\u00e9tape sup\u00e9rieure - Conseil des EPF","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ethrat.ch\/fr\/scinea-post\/limagerie-a-letape-superieure\/","og_locale":"fr_FR","og_type":"article","og_title":"L\u2019imagerie \u00e0 l\u2019\u00e9tape sup\u00e9rieure - Conseil des EPF","og_url":"https:\/\/ethrat.ch\/fr\/scinea-post\/limagerie-a-letape-superieure\/","og_site_name":"Conseil des EPF","article_modified_time":"2023-09-15T07:22:28+00:00","twitter_card":"summary_large_image","twitter_site":"@eth_rat","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ethrat.ch\/fr\/scinea-post\/limagerie-a-letape-superieure\/","url":"https:\/\/ethrat.ch\/fr\/scinea-post\/limagerie-a-letape-superieure\/","name":"L\u2019imagerie \u00e0 l\u2019\u00e9tape sup\u00e9rieure - Conseil des EPF","isPartOf":{"@id":"https:\/\/ethrat.ch\/de\/#website"},"datePublished":"2023-08-17T14:13:33+00:00","dateModified":"2023-09-15T07:22:28+00:00","breadcrumb":{"@id":"https:\/\/ethrat.ch\/fr\/scinea-post\/limagerie-a-letape-superieure\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ethrat.ch\/fr\/scinea-post\/limagerie-a-letape-superieure\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ethrat.ch\/fr\/scinea-post\/limagerie-a-letape-superieure\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ethrat.ch\/fr\/"},{"@type":"ListItem","position":2,"name":"Sciena Post","item":"https:\/\/ethrat.ch\/de\/scinea-post\/"},{"@type":"ListItem","position":3,"name":"L\u2019imagerie \u00e0 l\u2019\u00e9tape sup\u00e9rieure"}]},{"@type":"WebSite","@id":"https:\/\/ethrat.ch\/de\/#website","url":"https:\/\/ethrat.ch\/de\/","name":"ETH-Rat","description":"","publisher":{"@id":"https:\/\/ethrat.ch\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ethrat.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/ethrat.ch\/de\/#organization","name":"ETH-Rat","url":"https:\/\/ethrat.ch\/de\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ethrat.ch\/de\/#\/schema\/logo\/image\/","url":"https:\/\/ethrat.ch\/wp-content\/uploads\/2024\/04\/logo-white.svg","contentUrl":"https:\/\/ethrat.ch\/wp-content\/uploads\/2024\/04\/logo-white.svg","width":283,"height":81,"caption":"ETH-Rat"},"image":{"@id":"https:\/\/ethrat.ch\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/eth_rat","https:\/\/issuu.com\/ethrat","https:\/\/www.linkedin.com\/company\/eth-rat\/"]}]}},"_links":{"self":[{"href":"https:\/\/ethrat.ch\/fr\/wp-json\/wp\/v2\/sciena-post\/39488","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ethrat.ch\/fr\/wp-json\/wp\/v2\/sciena-post"}],"about":[{"href":"https:\/\/ethrat.ch\/fr\/wp-json\/wp\/v2\/types\/sciena-post"}],"author":[{"embeddable":true,"href":"https:\/\/ethrat.ch\/fr\/wp-json\/wp\/v2\/users\/11"}],"version-history":[{"count":0,"href":"https:\/\/ethrat.ch\/fr\/wp-json\/wp\/v2\/sciena-post\/39488\/revisions"}],"wp:attachment":[{"href":"https:\/\/ethrat.ch\/fr\/wp-json\/wp\/v2\/media?parent=39488"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ethrat.ch\/fr\/wp-json\/wp\/v2\/categories?post=39488"},{"taxonomy":"sciena_category","embeddable":true,"href":"https:\/\/ethrat.ch\/fr\/wp-json\/wp\/v2\/sciena_category?post=39488"},{"taxonomy":"sciena_topic","embeddable":true,"href":"https:\/\/ethrat.ch\/fr\/wp-json\/wp\/v2\/sciena_topic?post=39488"},{"taxonomy":"search-tag","embeddable":true,"href":"https:\/\/ethrat.ch\/fr\/wp-json\/wp\/v2\/search-tag?post=39488"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}